{"id":20485,"date":"2024-05-22T11:41:11","date_gmt":"2024-05-22T11:41:11","guid":{"rendered":"https:\/\/protectglobal.com\/case\/7-eleven\/"},"modified":"2025-01-13T11:49:12","modified_gmt":"2025-01-13T11:49:12","slug":"7-eleven","status":"publish","type":"case","link":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/","title":{"rendered":"7-Eleven"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-7-eleven\"><strong>7-Eleven<\/strong><\/h3>\n\n\n\n<p>Reitan Convenience Sweden AB poss\u00e8de des magasins 7-Eleven et Pressbyr\u00e5n dans toute la Su\u00e8de. Quelques ann\u00e9es auparavant, la soci\u00e9t\u00e9 a \u00e9t\u00e9 confront\u00e9e \u00e0 un tr\u00e8s gros probl\u00e8me de cambriolages qui survenaient fr\u00e9quemment dans ses magasins pour des vols de tabac, entre autres.  <\/p>\n\n\n\n<p>Entre 2013 et 2015, le taux de cambriolage des deux cha\u00eenes de magasins a augment\u00e9 de 170 %, ce qui est bien plus \u00e9lev\u00e9 que la moyenne des magasins comparables en Su\u00e8de. Et la compagnie d\u2019assurance de Reitan n\u2019a pas manqu\u00e9 de point\u00e9 du doigt ce probl\u00e8me. Il a \u00e9t\u00e9 demand\u00e9 \u00e0 Reitan de construire des magasins plus s\u00fbrs. Mais bien s\u00fbr, cela entra\u00eenerait des d\u00e9penses importantes pour la soci\u00e9t\u00e9. \u00ab M\u00eame si nous utilisions du verre de s\u00e9curit\u00e9, les cambrioleurs d\u00e9truiraient toute la fa\u00e7ade, et nous pr\u00e9voyons des co\u00fbts tr\u00e8s \u00e9lev\u00e9s pour reconstruire nos magasins \u00bb, a d\u00e9clar\u00e9 le responsable de la s\u00e9curit\u00e9 de Reitan Convenience Sweden AB.     <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"4480\" height=\"4480\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited.jpg\" alt=\"\" class=\"wp-image-23046 lazyload\" style=\"--smush-placeholder-width: 4480px; --smush-placeholder-aspect-ratio: 4480\/4480;width:850px;height:auto\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited.jpg 4480w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-300x300.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-1024x1024.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-150x150.jpg 150w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-768x768.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-1536x1536.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/09\/u6a8171-edited-2048x2048.jpg 2048w\" data-sizes=\"(max-width: 4480px) 100vw, 4480px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure><\/div>\n\n\n<p>Au lieu de cela, Reitan a install\u00e9 des g\u00e9n\u00e9rateurs de brouillard PROTECT\u00ae dans tous les nouveaux magasins et dans les magasins ayant subi des cambriolages. \u00ab Presque imm\u00e9diatement, et parce que l\u2019effet du brouillard de s\u00e9curit\u00e9 \u00e9tait d\u00e9j\u00e0 bien connu dans les milieux criminels, le nombre de cambriolages et de tentatives de cambriolage a diminu\u00e9 de moiti\u00e9 \u00bb, a d\u00e9clar\u00e9 le responsable de la s\u00e9curit\u00e9 de Reitan Convenience Sweden AB. Le taux de cambriolage de Reitan est revenu au m\u00eame niveau qu\u2019en 2005, ce qui est tr\u00e8s satisfaisant.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-une-prime-d-assurance-moins-elevee\"><strong>Une prime d\u2019assurance moins \u00e9lev\u00e9e <\/strong><\/h3>\n\n\n\n<p>En 2017, Reitan et ses deux cha\u00eenes de magasins ont atteint un taux magique, et l\u2019ann\u00e9e suivante, cette belle \u00e9volution s\u2019est poursuivie. \u00ab Selon nos statistiques, nous n\u2019avons jamais \u00e9t\u00e9 aussi bas depuis 10 ans. Notre compagnie d\u2019assurance nous a m\u00eame r\u00e9compens\u00e9s en r\u00e9duisant notre prime \u00bb, a conclu le directeur de la s\u00e9curit\u00e9 de Reitan Convenience Sweden AB.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-economie-d-argent-et-de-temps-perdu-en-arret-d-activite\"><strong>\u00c9conomie d\u2019argent et de temps perdu en arr\u00eat d\u2019activit\u00e9 <\/strong><\/h3>\n\n\n\n<p>\u00ab Le brouillard de s\u00e9curit\u00e9 joue un r\u00f4le cl\u00e9 dans notre r\u00e9ussite et notre strat\u00e9gie de s\u00e9curit\u00e9, car il prot\u00e8ge les biens jusqu\u2019\u00e0 l\u2019arriv\u00e9e de la police ou des agents de s\u00e9curit\u00e9. Il a \u00e9galement un effet pr\u00e9ventif. En \u00e9vitant de briser les fen\u00eatres et les portes, nous \u00e9conomisons \u00e0 la fois du temps et de l\u2019argent \u00bb, poursuit le responsable de la s\u00e9curit\u00e9 de Reitan Convenience Sweden AB.   <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"580\" height=\"356\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/7-eleven.png\" alt=\"\" class=\"wp-image-8935 lazyload\" style=\"--smush-placeholder-width: 580px; --smush-placeholder-aspect-ratio: 580\/356;width:1010px;height:auto\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/7-eleven.png 580w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/7-eleven-300x184.png 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/7-eleven-420x258.png 420w\" data-sizes=\"(max-width: 580px) 100vw, 580px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure><\/div>\n\n\n<p>\u00ab Nous avons choisi PROTECT\u2122 parce que les produits sont simples, les co\u00fbts de maintenance sont faibles et leurs syst\u00e8mes sont faciles \u00e0 int\u00e9grer \u00e0 nos syst\u00e8mes d\u2019alarme existants dans nos magasins \u00bb, a conclu le responsable de la s\u00e9curit\u00e9 de Reitan Convenience Sweden AB. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-securisez-votre-magasin-avec-les-generateurs-de-brouillard-protect\"><strong>S\u00e9curisez votre magasin avec les g\u00e9n\u00e9rateurs de brouillard PROTECT\u2122<\/strong><\/h3>\n\n\n\n<p>Prot\u00e9gez votre magasin de vente au d\u00e9tail contre les effractions et r\u00e9duisez les temps d\u2019arr\u00eat gr\u00e2ce aux g\u00e9n\u00e9rateurs de brouillard PROTECT\u2122, la solution de s\u00e9curit\u00e9 efficace et abordable \u00e0 laquelle Reitan Convenience Sweden AB fait confiance.<\/p>\n\n\n\n<p><a href=\"https:\/\/protectglobal.com\/fr\/get-in-touch\/\">Contactez<\/a><a href=\"https:\/\/protectglobal.com\/fr\/get-in-touch\/\" target=\"_blank\" rel=\"noreferrer noopener\">&#8211;<\/a><a href=\"https:\/\/protectglobal.com\/fr\/get-in-touch\/\">nous<\/a> d\u00e8s aujourd\u2019hui pour am\u00e9liorer la s\u00e9curit\u00e9 de votre magasin gr\u00e2ce \u00e0 nos solutions avanc\u00e9es de g\u00e9n\u00e9rateur de brouillard !<\/p>\n","protected":false},"featured_media":11530,"template":"","case-category":[85],"class_list":["post-20485","case","type-case","status-publish","has-post-thumbnail","hentry","case-category-vente-au-detail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>7-Eleven - Canons \u00e0 brouillard PROTECT\u2122<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7-Eleven\" \/>\n<meta property=\"og:description\" content=\"7-Eleven Reitan Convenience Sweden AB poss\u00e8de des magasins 7-Eleven et Pressbyr\u00e5n dans toute la Su\u00e8de. Quelques ann\u00e9es auparavant, la soci\u00e9t\u00e9 a \u00e9t\u00e9 confront\u00e9e \u00e0 un tr\u00e8s gros probl\u00e8me de cambriolages qui survenaient fr\u00e9quemment dans ses magasins pour des vols de tabac, entre autres. Entre 2013 et 2015, le taux de cambriolage des deux cha\u00eenes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/\" \/>\n<meta property=\"og:site_name\" content=\"Canons \u00e0 brouillard PROTECT\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PROTECTFogCannon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T11:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3668\" \/>\n\t<meta property=\"og:image:height\" content=\"2751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/\",\"name\":\"7-Eleven - Canons \u00e0 brouillard PROTECT\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg\",\"datePublished\":\"2024-05-22T11:41:11+00:00\",\"dateModified\":\"2025-01-13T11:49:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg\",\"width\":3668,\"height\":2751,\"caption\":\"7-eleven\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/7-eleven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7-Eleven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"name\":\"PROTECT Fog Cannons\u2122\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\",\"name\":\"PROTECT Fog Cannons\u2122\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"width\":90,\"height\":40,\"caption\":\"PROTECT Fog Cannons\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PROTECTFogCannon\\\/\",\"https:\\\/\\\/x.com\\\/PROTECTFOG\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protect-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PROTECTFogCannon\"],\"description\":\"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.\",\"email\":\"info@protectglobal.com\",\"telephone\":\"+45 8672 1881\",\"legalName\":\"PROTECT A\\\/S\",\"foundingDate\":\"2000-09-28\",\"vatID\":\"25687272\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"7-Eleven - Canons \u00e0 brouillard PROTECT\u2122","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/","og_locale":"fr_FR","og_type":"article","og_title":"7-Eleven","og_description":"7-Eleven Reitan Convenience Sweden AB poss\u00e8de des magasins 7-Eleven et Pressbyr\u00e5n dans toute la Su\u00e8de. Quelques ann\u00e9es auparavant, la soci\u00e9t\u00e9 a \u00e9t\u00e9 confront\u00e9e \u00e0 un tr\u00e8s gros probl\u00e8me de cambriolages qui survenaient fr\u00e9quemment dans ses magasins pour des vols de tabac, entre autres. Entre 2013 et 2015, le taux de cambriolage des deux cha\u00eenes de [&hellip;]","og_url":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/","og_site_name":"Canons \u00e0 brouillard PROTECT\u2122","article_publisher":"https:\/\/www.facebook.com\/PROTECTFogCannon\/","article_modified_time":"2025-01-13T11:49:12+00:00","og_image":[{"width":3668,"height":2751,"url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PROTECTFOG","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/","url":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/","name":"7-Eleven - Canons \u00e0 brouillard PROTECT\u2122","isPartOf":{"@id":"https:\/\/protectglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/#primaryimage"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg","datePublished":"2024-05-22T11:41:11+00:00","dateModified":"2025-01-13T11:49:12+00:00","breadcrumb":{"@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protectglobal.com\/fr\/case\/7-eleven\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/#primaryimage","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/ruby-khoesial-kgwpdpvxhh0-unsplash-scaled.jpg","width":3668,"height":2751,"caption":"7-eleven"},{"@type":"BreadcrumbList","@id":"https:\/\/protectglobal.com\/fr\/case\/7-eleven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/protectglobal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"7-Eleven"}]},{"@type":"WebSite","@id":"https:\/\/protectglobal.com\/fr\/#website","url":"https:\/\/protectglobal.com\/fr\/","name":"PROTECT Fog Cannons\u2122","description":"","publisher":{"@id":"https:\/\/protectglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protectglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/protectglobal.com\/fr\/#organization","name":"PROTECT Fog Cannons\u2122","url":"https:\/\/protectglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","width":90,"height":40,"caption":"PROTECT Fog Cannons\u2122"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PROTECTFogCannon\/","https:\/\/x.com\/PROTECTFOG","https:\/\/www.linkedin.com\/company\/protect-a-s\/","https:\/\/www.youtube.com\/user\/PROTECTFogCannon"],"description":"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.","email":"info@protectglobal.com","telephone":"+45 8672 1881","legalName":"PROTECT A\/S","foundingDate":"2000-09-28","vatID":"25687272","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case\/20485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media\/11530"}],"wp:attachment":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=20485"}],"wp:term":[{"taxonomy":"case-category","embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case-category?post=20485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}