{"id":20473,"date":"2024-05-22T11:39:38","date_gmt":"2024-05-22T11:39:38","guid":{"rendered":"https:\/\/protectglobal.com\/case\/depanneurs-et-magasins-dalcool\/"},"modified":"2025-01-13T11:49:59","modified_gmt":"2025-01-13T11:49:59","slug":"commerces-de-proximite-et-vendeurs-dalcool","status":"publish","type":"case","link":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/","title":{"rendered":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-commerces-de-proximite-et-vendeurs-d-alcool\"><strong>Commerces de proximit\u00e9 et vendeurs d\u2019alcool<\/strong><\/h3>\n\n\n\n<p>Des centaines de g\u00e9n\u00e9rateurs de brouillard ont \u00e9t\u00e9 install\u00e9s dans des espaces \u00e0 risque pour r\u00e9duire les vols. PROTECT New Zealand a remport\u00e9 un appel d\u2019offres lanc\u00e9 par le gouvernement, avec une vente de centaines de g\u00e9n\u00e9rateurs de brouillard \u00e0 des petits commerces de proximit\u00e9, des magasins d\u2019alcool et des stations-service g\u00e9r\u00e9es par des ind\u00e9pendants. <\/p>\n\n\n\n<p>Auparavant, une augmentation spectaculaire de la taxe sur le tabac avait entra\u00een\u00e9 un nombre de vols de jour comme de nuit sup\u00e9rieur \u00e0 la normale. Des propri\u00e9taires de commerces ont \u00e9t\u00e9 bless\u00e9s, voire tu\u00e9s, ce qui a naturellement provoqu\u00e9 une vive \u00e9motion. Des protestations et des demandes ont \u00e9t\u00e9 adress\u00e9es au gouvernement pour obtenir une meilleure protection. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-vous-ne-pourrez-pas-rester-dans-les-parages-lorsque-le-generateur-de-brouillard-s-activera\"><strong>Vous ne pourrez pas rester dans les parages lorsque le g\u00e9n\u00e9rateur de brouillard s\u2019activera <\/strong><\/h3>\n\n\n\n<p>Les g\u00e9n\u00e9rateurs de brouillard sont d\u00e9clench\u00e9s par des capteurs sans fil qui peuvent \u00eatre plac\u00e9s dans une boutique ou sur une personne. L\u2019\u00e9pais mur de brouillard cr\u00e9e une barri\u00e8re entre les malfaiteurs et le personnel, et leur objectif final, \u00e0 savoir l\u2019argent ou les cigarettes.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"744\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/foqus_frit_fog_low.jpg\" alt=\"\" class=\"wp-image-3175 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/foqus_frit_fog_low.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/foqus_frit_fog_low-413x300.jpg 413w, https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/foqus_frit_fog_low-300x218.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/foqus_frit_fog_low-768x558.jpg 768w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/744;\" \/><\/figure>\n\n\n\n<p>\u00ab Le d\u00e9ploiement du brouillard est tr\u00e8s rapide et il remplit l\u2019espace tr\u00e8s vite. Il repousse les malfaiteurs \u00bb, a d\u00e9clar\u00e9 le surintendant Jill Rogers, de la police n\u00e9o-z\u00e9landaise. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-l-incident-de-hamilton-montre-l-efficacite\"><strong>L\u2019incident de Hamilton montre l\u2019efficacit\u00e9 <\/strong><\/h3>\n\n\n\n<p>Trois hommes masqu\u00e9s ont pris d\u2019assaut une boutique de Hamilton en brandissant une planche de bois et un couteau, un lundi matin. Mais un g\u00e9n\u00e9rateur de brouillard les a fait fuir les mains vides.  <\/p>\n\n\n\n<p>4 malfaiteurs \u00e9taient impliqu\u00e9s, une femme tenant la porte \u00e9lectronique ouverte, tandis que les trois hommes entraient dans la boutique avec leurs armes. Mais apr\u00e8s l\u2019activation du g\u00e9n\u00e9rateur de brouillard, le groupe s\u2019est enfui. Personne n\u2019a \u00e9t\u00e9 bless\u00e9.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-diminution-de-40-des-vols\"><strong>Diminution de 40 % des vols <\/strong><\/h3>\n\n\n\n<p>Le directeur national de la pr\u00e9vention, le surintendant Eric Tibbott, a d\u00e9clar\u00e9 que les g\u00e9n\u00e9rateurs de brouillard avaient entra\u00een\u00e9 une diminution de 40 % des vols aggrav\u00e9s signal\u00e9s. <\/p>\n\n\n\n<p>\u00ab L\u00e0 o\u00f9 nous avons install\u00e9 les g\u00e9n\u00e9rateurs de brouillard, nous avons \u00e9galement v\u00e9rifi\u00e9 la vid\u00e9osurveillance et nous avons constat\u00e9 que tr\u00e8s peu de biens avaient \u00e9t\u00e9 vol\u00e9s et qu\u2019aucune violence n\u2019avait \u00e9t\u00e9 commise \u00e0 l\u2019encontre de la victime \u00e0 ces endroits, de sorte que le syst\u00e8me est tr\u00e8s, tr\u00e8s efficace \u00bb, conclut M. Tibbott. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"760\" height=\"415\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/03\/the-difference-between-security-fog-and-smoke-_760-_-515px_.jpg\" alt=\"\" class=\"wp-image-4031 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/03\/the-difference-between-security-fog-and-smoke-_760-_-515px_.jpg 760w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/03\/the-difference-between-security-fog-and-smoke-_760-_-515px_-420x229.jpg 420w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/03\/the-difference-between-security-fog-and-smoke-_760-_-515px_-300x164.jpg 300w\" data-sizes=\"(max-width: 760px) 100vw, 760px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 760px; --smush-placeholder-aspect-ratio: 760\/415;\" \/><\/figure>\n\n\n\n<p>Le ministre de la police Stuart Nash : <br>\u00ab Les g\u00e9n\u00e9rateurs de brouillard ont \u00e9t\u00e9 activ\u00e9s par des employ\u00e9s dans 29 entreprises et, dans tous les cas, il n\u2019y a pas eu de blessures pour le personnel et des pertes mat\u00e9rielles minimes pour les entreprises. Il y a eu 21 vols en d\u00e9cembre 2019, soit une baisse de plus de 70 % par rapport aux 78 vols d\u2019avril 2017. \u00bb <\/p>\n\n\n\n<p>Source : <a href=\"http:\/\/stuff.co.nz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stuff.co.nz<\/a> <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-contactez-nous-des-maintenant-pour-en-savoir-plus-et-securiser-votre-magasin-avec-les-generateurs-de-brouillard-protect\"><strong><a href=\"https:\/\/protectglobal.com\/fr\/get-in-touch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Contactez-nous<\/a> d\u00e8s maintenant pour en savoir plus et s\u00e9curiser votre magasin avec les g\u00e9n\u00e9rateurs de brouillard PROTECT !<\/strong><\/h3>\n\n\n\n<p>Investissez dans les g\u00e9n\u00e9rateurs de brouillard PROTECT pour assurer la s\u00e9curit\u00e9 de votre commerce, de vos employ\u00e9s et de vos clients. D\u00e9couvrez la tranquillit\u00e9 d\u2019esprit que procure le fait de savoir que votre magasin est prot\u00e9g\u00e9 contre les vols et les incidents violents.  <\/p>\n","protected":false},"featured_media":11537,"template":"","case-category":[85],"class_list":["post-20473","case","type-case","status-publish","has-post-thumbnail","hentry","case-category-vente-au-detail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Commerces de proximit\u00e9 et vendeurs d\u2019alcool - Canons \u00e0 brouillard PROTECT\u2122<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commerces de proximit\u00e9 et vendeurs d\u2019alcool\" \/>\n<meta property=\"og:description\" content=\"Commerces de proximit\u00e9 et vendeurs d\u2019alcool Des centaines de g\u00e9n\u00e9rateurs de brouillard ont \u00e9t\u00e9 install\u00e9s dans des espaces \u00e0 risque pour r\u00e9duire les vols. PROTECT New Zealand a remport\u00e9 un appel d\u2019offres lanc\u00e9 par le gouvernement, avec une vente de centaines de g\u00e9n\u00e9rateurs de brouillard \u00e0 des petits commerces de proximit\u00e9, des magasins d\u2019alcool et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/\" \/>\n<meta property=\"og:site_name\" content=\"Canons \u00e0 brouillard PROTECT\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PROTECTFogCannon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T11:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/rivage-z5aktkhrjsq-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/\",\"name\":\"Commerces de proximit\u00e9 et vendeurs d\u2019alcool - Canons \u00e0 brouillard PROTECT\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rivage-z5aktkhrjsq-unsplash-scaled.jpg\",\"datePublished\":\"2024-05-22T11:39:38+00:00\",\"dateModified\":\"2025-01-13T11:49:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rivage-z5aktkhrjsq-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rivage-z5aktkhrjsq-unsplash-scaled.jpg\",\"width\":4032,\"height\":3024,\"caption\":\"liquor stores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/commerces-de-proximite-et-vendeurs-dalcool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commerces de proximit\u00e9 et vendeurs d\u2019alcool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"name\":\"PROTECT Fog Cannons\u2122\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\",\"name\":\"PROTECT Fog Cannons\u2122\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"width\":90,\"height\":40,\"caption\":\"PROTECT Fog Cannons\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PROTECTFogCannon\\\/\",\"https:\\\/\\\/x.com\\\/PROTECTFOG\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protect-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PROTECTFogCannon\"],\"description\":\"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.\",\"email\":\"info@protectglobal.com\",\"telephone\":\"+45 8672 1881\",\"legalName\":\"PROTECT A\\\/S\",\"foundingDate\":\"2000-09-28\",\"vatID\":\"25687272\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool - Canons \u00e0 brouillard PROTECT\u2122","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/","og_locale":"fr_FR","og_type":"article","og_title":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool","og_description":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool Des centaines de g\u00e9n\u00e9rateurs de brouillard ont \u00e9t\u00e9 install\u00e9s dans des espaces \u00e0 risque pour r\u00e9duire les vols. PROTECT New Zealand a remport\u00e9 un appel d\u2019offres lanc\u00e9 par le gouvernement, avec une vente de centaines de g\u00e9n\u00e9rateurs de brouillard \u00e0 des petits commerces de proximit\u00e9, des magasins d\u2019alcool et [&hellip;]","og_url":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/","og_site_name":"Canons \u00e0 brouillard PROTECT\u2122","article_publisher":"https:\/\/www.facebook.com\/PROTECTFogCannon\/","article_modified_time":"2025-01-13T11:49:59+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/rivage-z5aktkhrjsq-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PROTECTFOG","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/","url":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/","name":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool - Canons \u00e0 brouillard PROTECT\u2122","isPartOf":{"@id":"https:\/\/protectglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/#primaryimage"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/rivage-z5aktkhrjsq-unsplash-scaled.jpg","datePublished":"2024-05-22T11:39:38+00:00","dateModified":"2025-01-13T11:49:59+00:00","breadcrumb":{"@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/#primaryimage","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/rivage-z5aktkhrjsq-unsplash-scaled.jpg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/rivage-z5aktkhrjsq-unsplash-scaled.jpg","width":4032,"height":3024,"caption":"liquor stores"},{"@type":"BreadcrumbList","@id":"https:\/\/protectglobal.com\/fr\/case\/commerces-de-proximite-et-vendeurs-dalcool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/protectglobal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Commerces de proximit\u00e9 et vendeurs d\u2019alcool"}]},{"@type":"WebSite","@id":"https:\/\/protectglobal.com\/fr\/#website","url":"https:\/\/protectglobal.com\/fr\/","name":"PROTECT Fog Cannons\u2122","description":"","publisher":{"@id":"https:\/\/protectglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protectglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/protectglobal.com\/fr\/#organization","name":"PROTECT Fog Cannons\u2122","url":"https:\/\/protectglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","width":90,"height":40,"caption":"PROTECT Fog Cannons\u2122"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PROTECTFogCannon\/","https:\/\/x.com\/PROTECTFOG","https:\/\/www.linkedin.com\/company\/protect-a-s\/","https:\/\/www.youtube.com\/user\/PROTECTFogCannon"],"description":"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.","email":"info@protectglobal.com","telephone":"+45 8672 1881","legalName":"PROTECT A\/S","foundingDate":"2000-09-28","vatID":"25687272","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case\/20473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media\/11537"}],"wp:attachment":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=20473"}],"wp:term":[{"taxonomy":"case-category","embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case-category?post=20473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}