{"id":20017,"date":"2024-05-22T13:32:39","date_gmt":"2024-05-22T13:32:39","guid":{"rendered":"https:\/\/protectglobal.com\/case\/domicile-prive-au-danemark\/"},"modified":"2025-01-13T11:46:49","modified_gmt":"2025-01-13T11:46:49","slug":"les-domiciles-au-danemark","status":"publish","type":"case","link":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/","title":{"rendered":"Les domiciles au Danemark"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-les-particuliers-se-protegent-contre-le-nombre-croissant-de-cambriolages\"><strong>Les particuliers se prot\u00e8gent contre le nombre croissant de cambriolages <\/strong><\/h3>\n\n\n\n<p>Les cambrioleurs op\u00e8rent souvent dans des quartiers o\u00f9 ils peuvent trouver des habitations dans lesquelles il est facile de p\u00e9n\u00e9trer et d\u2019o\u00f9 il est facile de s\u2019\u00e9chapper. Ils esp\u00e8rent pouvoir rapidement trouver de l\u2019argent, des bijoux et d\u2019autres objets faciles \u00e0 revendre. Les cambriolages sont ex\u00e9cut\u00e9s rapidement. Il est donc important de s\u00e9curiser les voies d\u2019acc\u00e8s \u00e0 l\u2019habitation et de veiller \u00e0 ce que le voleur soit imm\u00e9diatement poursuivi. Sinon, comme beaucoup d\u2019autres Danois, vous risquez de rentrer chez vous dans une maison compl\u00e8tement d\u00e9vast\u00e9e. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-1024x683.jpg\" alt=\"\" class=\"wp-image-11627 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-1024x683.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-300x200.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-768x512.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-1536x1024.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-2048x1365.jpg 2048w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev6930-420x280.jpg 420w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-analyse-des-besoins-et-des-opportunites\"><strong>Analyse des besoins et des opportunit\u00e9s <\/strong><\/h3>\n\n\n\n<p>\u00ab Nous avons subi un cambriolage il y a 15 ans, puis un autre au d\u00e9but de l\u2019ann\u00e9e \u00bb, explique un avocat de la r\u00e9gion d\u2019Aarhus en 2016, qui a d\u00e9sormais choisi de s\u00e9curiser les portes et les fen\u00eatres de sa maison et de faire installer une alarme anti-effraction \u00e9lectronique avec brouillard de s\u00e9curit\u00e9 qui, en quelques secondes, remplit la pi\u00e8ce de la maison d\u2019un brouillard opaque afin que le voleur ne puisse pas trouver les objets de valeur et prenne la fuite. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-1024x683.jpg\" alt=\"\" class=\"wp-image-11634 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-1024x683.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-300x200.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-768x512.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-1536x1024.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-2048x1365.jpg 2048w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/protectharlev7006-420x280.jpg 420w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/figure>\n\n\n\n<p>L\u2019avocat a constat\u00e9 que les cambriolages se produisent par vagues. Apr\u00e8s le cambriolage, la famille a \u00e9tudi\u00e9 les diff\u00e9rentes options et a convenu qu\u2019elle ne voulait absolument pas avoir de cam\u00e9ras \u00e0 l\u2019int\u00e9rieur ni autour de la maison. Suivant les conseils de leur installateur d\u2019alarme, ils ont choisi de moderniser les serrures de la maison et de s\u00e9curiser les fen\u00eatres, ainsi que d\u2019installer 2 g\u00e9n\u00e9rateurs de brouillard PROTECT Xtratus\u00ae qui se d\u00e9clenchent lorsque l\u2019alarme \u00e9lectronique est activ\u00e9e. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-compagnies-d-assurance-recommandent-le-brouillard-de-securite\"><strong>Les compagnies d\u2019assurance recommandent le brouillard de s\u00e9curit\u00e9 <\/strong><\/h3>\n\n\n\n<p>Le responsable du d\u00e9veloppement du business de la compagnie d\u2019assurance Topdanmark a vu un potentiel consid\u00e9rable dans le brouillard de s\u00e9curit\u00e9 comme moyen de pr\u00e9vention contre les cambriolages dans les domiciles priv\u00e9s. <\/p>\n\n\n\n<p>\u00ab Chaque ann\u00e9e, de nombreux Danois sont victimes de cambriolages, au cours desquels les voleurs s\u2019enfuient avec des meubles design, des bijoux et d\u2019autres objets de valeur. Un syst\u00e8me de brouillard de s\u00e9curit\u00e9 install\u00e9 par un professionnel peut grandement contribuer \u00e0 s\u00e9curiser les objets de valeur du domicile et constitue donc un bon compl\u00e9ment aux m\u00e9thodes de s\u00e9curit\u00e9 m\u00e9caniques et \u00e9lectroniques, car il remplit une ou plusieurs pi\u00e8ces d\u2019un brouillard opaque en quelques secondes. Le brouillard de s\u00e9curit\u00e9 peut ainsi \u00e0 la fois agir comme mesure pr\u00e9ventive et contribuer \u00e0 faire \u00e9chouer les tentatives de cambriolage, car le voleur ne peut pas s\u2019y retrouver dans le brouillard \u00bb, explique le responsable du d\u00e9veloppement du business.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-protegez-votre-domicile-avec-le-brouillard-de-securite-protect\"><strong>Prot\u00e9gez votre domicile avec le brouillard de s\u00e9curit\u00e9 PROTECT\u2122<\/strong><\/h3>\n\n\n\n<p>S\u00e9curisez vos biens de valeur et dissuadez efficacement les cambrioleurs gr\u00e2ce aux syst\u00e8mes de brouillard de s\u00e9curit\u00e9 PROTECT\u2122, auxquels font confiance les propri\u00e9taires et recommand\u00e9s par les compagnies d\u2019assurance.<\/p>\n\n\n\n<p><a href=\"https:\/\/protectglobal.com\/fr\/get-in-touch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Contactez-nous<\/a> d\u00e8s aujourd\u2019hui pour renforcer votre domicile contre le cambriolage !<\/p>\n","protected":false},"featured_media":8471,"template":"","case-category":[61],"class_list":["post-20017","case","type-case","status-publish","has-post-thumbnail","hentry","case-category-domestique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les domiciles au Danemark - Canons \u00e0 brouillard PROTECT\u2122<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les domiciles au Danemark\" \/>\n<meta property=\"og:description\" content=\"Les particuliers se prot\u00e8gent contre le nombre croissant de cambriolages Les cambrioleurs op\u00e8rent souvent dans des quartiers o\u00f9 ils peuvent trouver des habitations dans lesquelles il est facile de p\u00e9n\u00e9trer et d\u2019o\u00f9 il est facile de s\u2019\u00e9chapper. Ils esp\u00e8rent pouvoir rapidement trouver de l\u2019argent, des bijoux et d\u2019autres objets faciles \u00e0 revendre. Les cambriolages sont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/\" \/>\n<meta property=\"og:site_name\" content=\"Canons \u00e0 brouillard PROTECT\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PROTECTFogCannon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T11:46:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectharlev7010-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/\",\"name\":\"Les domiciles au Danemark - Canons \u00e0 brouillard PROTECT\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectharlev7010-scaled.jpg\",\"datePublished\":\"2024-05-22T13:32:39+00:00\",\"dateModified\":\"2025-01-13T11:46:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectharlev7010-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectharlev7010-scaled.jpg\",\"width\":5616,\"height\":3744,\"caption\":\"living room with fog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/case\\\/les-domiciles-au-danemark\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les domiciles au Danemark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"name\":\"PROTECT Fog Cannons\u2122\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#organization\",\"name\":\"PROTECT Fog Cannons\u2122\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"width\":90,\"height\":40,\"caption\":\"PROTECT Fog Cannons\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PROTECTFogCannon\\\/\",\"https:\\\/\\\/x.com\\\/PROTECTFOG\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protect-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PROTECTFogCannon\"],\"description\":\"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.\",\"email\":\"info@protectglobal.com\",\"telephone\":\"+45 8672 1881\",\"legalName\":\"PROTECT A\\\/S\",\"foundingDate\":\"2000-09-28\",\"vatID\":\"25687272\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les domiciles au Danemark - Canons \u00e0 brouillard PROTECT\u2122","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/","og_locale":"fr_FR","og_type":"article","og_title":"Les domiciles au Danemark","og_description":"Les particuliers se prot\u00e8gent contre le nombre croissant de cambriolages Les cambrioleurs op\u00e8rent souvent dans des quartiers o\u00f9 ils peuvent trouver des habitations dans lesquelles il est facile de p\u00e9n\u00e9trer et d\u2019o\u00f9 il est facile de s\u2019\u00e9chapper. Ils esp\u00e8rent pouvoir rapidement trouver de l\u2019argent, des bijoux et d\u2019autres objets faciles \u00e0 revendre. Les cambriolages sont [&hellip;]","og_url":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/","og_site_name":"Canons \u00e0 brouillard PROTECT\u2122","article_publisher":"https:\/\/www.facebook.com\/PROTECTFogCannon\/","article_modified_time":"2025-01-13T11:46:49+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectharlev7010-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PROTECTFOG","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/","url":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/","name":"Les domiciles au Danemark - Canons \u00e0 brouillard PROTECT\u2122","isPartOf":{"@id":"https:\/\/protectglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/#primaryimage"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectharlev7010-scaled.jpg","datePublished":"2024-05-22T13:32:39+00:00","dateModified":"2025-01-13T11:46:49+00:00","breadcrumb":{"@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/#primaryimage","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectharlev7010-scaled.jpg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectharlev7010-scaled.jpg","width":5616,"height":3744,"caption":"living room with fog"},{"@type":"BreadcrumbList","@id":"https:\/\/protectglobal.com\/fr\/case\/les-domiciles-au-danemark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/protectglobal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les domiciles au Danemark"}]},{"@type":"WebSite","@id":"https:\/\/protectglobal.com\/fr\/#website","url":"https:\/\/protectglobal.com\/fr\/","name":"PROTECT Fog Cannons\u2122","description":"","publisher":{"@id":"https:\/\/protectglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protectglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/protectglobal.com\/fr\/#organization","name":"PROTECT Fog Cannons\u2122","url":"https:\/\/protectglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","width":90,"height":40,"caption":"PROTECT Fog Cannons\u2122"},"image":{"@id":"https:\/\/protectglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PROTECTFogCannon\/","https:\/\/x.com\/PROTECTFOG","https:\/\/www.linkedin.com\/company\/protect-a-s\/","https:\/\/www.youtube.com\/user\/PROTECTFogCannon"],"description":"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.","email":"info@protectglobal.com","telephone":"+45 8672 1881","legalName":"PROTECT A\/S","foundingDate":"2000-09-28","vatID":"25687272","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case\/20017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media\/8471"}],"wp:attachment":[{"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=20017"}],"wp:term":[{"taxonomy":"case-category","embeddable":true,"href":"https:\/\/protectglobal.com\/fr\/wp-json\/wp\/v2\/case-category?post=20017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}