{"id":4047,"date":"2021-03-22T11:55:00","date_gmt":"2021-03-22T11:55:00","guid":{"rendered":"https:\/\/protectglobal.com\/?p=4047"},"modified":"2024-10-03T08:49:53","modified_gmt":"2024-10-03T08:49:53","slug":"la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla","status":"publish","type":"post","link":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/","title":{"rendered":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La activaci\u00f3n de la niebla de seguridad es tambi\u00e9n la activaci\u00f3n de la respuesta de estr\u00e9s agudo del ladr\u00f3n<\/h2>\n\n<p>En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla, ya sea en relaci\u00f3n con un robo o un atraco.<\/p>\n\n<p>Especialmente en relaci\u00f3n con la seguridad contra robos en, por ejemplo, quioscos, a menudo recibimos preguntas sobre los patrones de reacci\u00f3n de los delincuentes cuando se acaba de activar la niebla de seguridad.\n\u00bfHuyen o se quedan? <\/p>\n\n<p>Est\u00e1 en lo m\u00e1s profundo de nosotros, los humanos, huir cuando tenemos miedo en lugar de continuar ciegamente hacia algo desconocido, y especialmente hacia algo en lo que no puedes orientarte f\u00edsicamente y no sabes c\u00f3mo escapar.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-1024x683.jpg\" alt=\"\" class=\"wp-image-7180 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-1024x683.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-300x200.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-768x512.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-1536x1024.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-2048x1365.jpg 2048w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin349-420x280.jpg 420w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/figure>\n\n<p>Simplificando, se trata de una colaboraci\u00f3n entre las partes de la am\u00edgdala* y el hipot\u00e1lamo** de nuestro cerebro que activan la respuesta del cuerpo (por ejemplo, el estr\u00e9s y la huida) cuando detecta una amenaza grave.\nLa am\u00edgdala, en particular, es crucial para cuando el cuerpo se pone en alerta.\nCuando esto ocurre, la necesidad de supervivencia y protecci\u00f3n dominar\u00e1 sobre las necesidades menos urgentes, como la ganancia econ\u00f3mica y el hambre.  <\/p>\n\n<p>Para una persona que se dedique o est\u00e9 a punto de dedicarse a algo delictivo, el sonido de las sirenas de la polic\u00eda o el sonido del encendido de un Ca\u00f1\u00f3n de Niebla desencadenar\u00e1n una se\u00f1al de amenaza en la am\u00edgdala y el hipocampo de esa persona***.\nLa combinaci\u00f3n de los sonidos, la propia niebla de seguridad y la consiguiente reducci\u00f3n de la visibilidad utiliza los est\u00edmulos asociados a la respuesta de miedo de la am\u00edgdala en los delincuentes. <\/p>\n\n<p>Por tanto, la niebla de seguridad est\u00e1 dise\u00f1ada espec\u00edficamente para activar el estado de alerta del delincuente y evocar una respuesta de huida inmediata, aprovechando la necesidad autom\u00e1tica del cerebro de priorizar la supervivencia sobre el beneficio econ\u00f3mico.<\/p>\n\n<p>Por eso, una y otra vez, cuando se activa la niebla, experimentamos que un ladr\u00f3n o atracador huye inmediatamente del lugar en lugar de dirigir su atenci\u00f3n a la \u00abpresa\u00bb, o peor a\u00fan, a las personas inocentes que se encuentran en la habitaci\u00f3n.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-1024x683.jpg\" alt=\"\" class=\"wp-image-7560 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-1024x683.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-300x200.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-768x512.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-1536x1024.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-2048x1365.jpg 2048w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-420x280.jpg 420w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/figure>\n\n<p>Esta informaci\u00f3n esencial ha sido confirmada por el Centro de Conocimientos de Psico-Traumatolog\u00eda del Departamento de Psicolog\u00eda de la Universidad del Sur de Dinamarca.<\/p>\n\n<p>NOTA\nComo con cualquier otro equipo de seguridad, es importante informar al personal\/usuarios sobre el Ca\u00f1\u00f3n de Niebla y su funcionamiento.\nQu\u00e9 hacer en caso de activaci\u00f3n defectuosa de la niebla, y sobre todo c\u00f3mo actuar ante una situaci\u00f3n de robo en la que se active un Ca\u00f1\u00f3n de Niebla.  <\/p>\n\n<p>* Peque\u00f1a zona del l\u00f3bulo temporal del cerebro que, entre otras cosas, se encarga del miedo y de las reacciones defensivas<\/p>\n\n<p>** Parte anterior del cerebro, que controla, por ejemplo, la temperatura, las hormonas, el metabolismo, la sed, el hambre, el comportamiento sexual, el miedo, la ira y diversos ritmos de actividad.<\/p>\n\n<p>*** El hipocampo es una regi\u00f3n del cerebro situada en el l\u00f3bulo temporal medio.\nTenemos dos hipocampos, uno a cada lado del cerebro.\nEl hipocampo forma parte del sistema l\u00edmbico y desempe\u00f1a un papel en la orientaci\u00f3n y la memoria humanas.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La activaci\u00f3n de la niebla de seguridad es tambi\u00e9n la activaci\u00f3n de la respuesta de estr\u00e9s agudo del ladr\u00f3n En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla, ya sea en relaci\u00f3n con un robo o un atraco. Especialmente en relaci\u00f3n con la seguridad [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":7566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-4047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-information-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla - Ca\u00f1ones de niebla PROTECT\u2122<\/title>\n<meta name=\"description\" content=\"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla\" \/>\n<meta property=\"og:description\" content=\"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/\" \/>\n<meta property=\"og:site_name\" content=\"Ca\u00f1ones de niebla PROTECT\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PROTECTFogCannon\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-22T11:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T08:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:site\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/\"},\"author\":{\"name\":\"Marcus\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/c7ad9a8c618871f998e876741a5e78d6\"},\"headline\":\"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla\",\"datePublished\":\"2021-03-22T11:55:00+00:00\",\"dateModified\":\"2024-10-03T08:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/\"},\"wordCount\":587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectbreakin319.jpg\",\"articleSection\":[\"Informaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/\",\"name\":\"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla - Ca\u00f1ones de niebla PROTECT\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectbreakin319.jpg\",\"datePublished\":\"2021-03-22T11:55:00+00:00\",\"dateModified\":\"2024-10-03T08:49:53+00:00\",\"description\":\"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectbreakin319.jpg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/protectbreakin319.jpg\",\"width\":8256,\"height\":5504,\"caption\":\"burglar meets security fog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/\",\"name\":\"PROTECT Fog Cannons\u2122\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#organization\",\"name\":\"PROTECT Fog Cannons\u2122\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"width\":90,\"height\":40,\"caption\":\"PROTECT Fog Cannons\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PROTECTFogCannon\\\/\",\"https:\\\/\\\/x.com\\\/PROTECTFOG\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protect-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PROTECTFogCannon\"],\"description\":\"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.\",\"email\":\"info@protectglobal.com\",\"telephone\":\"+45 8672 1881\",\"legalName\":\"PROTECT A\\\/S\",\"foundingDate\":\"2000-09-28\",\"vatID\":\"25687272\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/c7ad9a8c618871f998e876741a5e78d6\",\"name\":\"Marcus\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/es\\\/author\\\/marcuspro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla - Ca\u00f1ones de niebla PROTECT\u2122","description":"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/","og_locale":"es_ES","og_type":"article","og_title":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla","og_description":"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.","og_url":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/","og_site_name":"Ca\u00f1ones de niebla PROTECT\u2122","article_publisher":"https:\/\/www.facebook.com\/PROTECTFogCannon\/","article_published_time":"2021-03-22T11:55:00+00:00","article_modified_time":"2024-10-03T08:49:53+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319-1024x683.jpg","type":"image\/jpeg"}],"author":"Marcus","twitter_card":"summary_large_image","twitter_creator":"@PROTECTFOG","twitter_site":"@PROTECTFOG","twitter_misc":{"Escrito por":"Marcus","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#article","isPartOf":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/"},"author":{"name":"Marcus","@id":"https:\/\/protectglobal.com\/es\/#\/schema\/person\/c7ad9a8c618871f998e876741a5e78d6"},"headline":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla","datePublished":"2021-03-22T11:55:00+00:00","dateModified":"2024-10-03T08:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/protectglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319.jpg","articleSection":["Informaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/","url":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/","name":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla - Ca\u00f1ones de niebla PROTECT\u2122","isPartOf":{"@id":"https:\/\/protectglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#primaryimage"},"image":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319.jpg","datePublished":"2021-03-22T11:55:00+00:00","dateModified":"2024-10-03T08:49:53+00:00","description":"En muchos contextos nos dicen que los ladrones huyen inmediatamente del lugar cuando activan uno de nuestros Ca\u00f1ones de Niebla.","breadcrumb":{"@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#primaryimage","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319.jpg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/protectbreakin319.jpg","width":8256,"height":5504,"caption":"burglar meets security fog"},{"@type":"BreadcrumbList","@id":"https:\/\/protectglobal.com\/es\/la-reaccion-de-un-ladron-a-la-activacion-de-un-canon-de-niebla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/protectglobal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reacci\u00f3n de un ladr\u00f3n ante la activaci\u00f3n de un ca\u00f1\u00f3n de niebla"}]},{"@type":"WebSite","@id":"https:\/\/protectglobal.com\/es\/#website","url":"https:\/\/protectglobal.com\/es\/","name":"PROTECT Fog Cannons\u2122","description":"","publisher":{"@id":"https:\/\/protectglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protectglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/protectglobal.com\/es\/#organization","name":"PROTECT Fog Cannons\u2122","url":"https:\/\/protectglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protectglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","width":90,"height":40,"caption":"PROTECT Fog Cannons\u2122"},"image":{"@id":"https:\/\/protectglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PROTECTFogCannon\/","https:\/\/x.com\/PROTECTFOG","https:\/\/www.linkedin.com\/company\/protect-a-s\/","https:\/\/www.youtube.com\/user\/PROTECTFogCannon"],"description":"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.","email":"info@protectglobal.com","telephone":"+45 8672 1881","legalName":"PROTECT A\/S","foundingDate":"2000-09-28","vatID":"25687272","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/protectglobal.com\/es\/#\/schema\/person\/c7ad9a8c618871f998e876741a5e78d6","name":"Marcus","url":"https:\/\/protectglobal.com\/es\/author\/marcuspro\/"}]}},"_links":{"self":[{"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/posts\/4047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/comments?post=4047"}],"version-history":[{"count":4,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/posts\/4047\/revisions"}],"predecessor-version":[{"id":23665,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/posts\/4047\/revisions\/23665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/media\/7566"}],"wp:attachment":[{"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/media?parent=4047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/categories?post=4047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protectglobal.com\/es\/wp-json\/wp\/v2\/tags?post=4047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}