{"id":20462,"date":"2024-05-22T11:30:39","date_gmt":"2024-05-22T11:30:39","guid":{"rendered":"https:\/\/protectglobal.com\/case\/apotheke\/"},"modified":"2024-12-16T13:17:12","modified_gmt":"2024-12-16T13:17:12","slug":"apotheke","status":"publish","type":"case","link":"https:\/\/protectglobal.com\/de\/case\/apotheke\/","title":{"rendered":"Apotheke"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-positive-erfahrungen-mit-nebelsicherheit-fuhren-zu-neuen-installationen-in-der-kolind-apotheke-in-danemark\"><strong>Positive Erfahrungen mit Nebelsicherheit f\u00fchren zu neuen Installationen in der Kolind Apotheke in D\u00e4nemark<\/strong><\/h3>\n\n\n\n<p>Nachdem die Apothekerin Lisbet H\u00f8gh in der Vergangenheit gute Erfahrungen mit Nebelschutz gemacht hat, hat sie beschlossen, in ihrem neuen Gesch\u00e4ftszentrum in der d\u00e4nischen Stadt Kolind Nebelkanonen zu installieren.\nDer Nebel ist sowohl mit den Medikamenten als auch mit dem pharmazeutischen Roboter, der hinter dem Tresen arbeitet, kompatibel.\nDer Nebel passiert ohne Probleme sowohl die Medikamente als auch den neuen Arzneimittelroboter der Apotheke.  <\/p>\n\n\n\n<p>Leider sind Apotheken ein h\u00e4ufiges Ziel f\u00fcr Einbr\u00fcche.\nAuch eine Apotheke hatte unter Einbr\u00fcchen zu leiden &#8211; das hei\u00dft, bis sie vor f\u00fcnf Jahren Nebelkanonen in einer Apotheke installierten.\nSeitdem hat der Laden nicht einmal mehr einen Einbruchsversuch erlebt.\nDasselbe gilt f\u00fcr eine andere Einzelhandelsapotheke, in der sie eine Nebelsicherung installiert haben.\n&#8222;Wir haben eine Menge f\u00fcr die Sicherheit getan. Aber allein die Vermeidung von Einbruchsversuchen ist das alles wert&#8220;, sagt Lisbet H\u00f8gh, die leitende Apothekerin.    <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2560\" height=\"1838\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-scaled.jpg\" alt=\"\" class=\"wp-image-11703 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-scaled.jpg 2560w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-300x215.jpg 300w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-1024x735.jpg 1024w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-768x551.jpg 768w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-1536x1103.jpg 1536w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-2048x1470.jpg 2048w, https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/06\/istock_000015972967large-edited-418x300.jpg 418w\" data-sizes=\"(max-width: 2560px) 100vw, 2560px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1838;\" \/><\/figure>\n\n\n\n<p>Ihre neueste Apotheke, die jetzt er\u00f6ffnet wurde, ist ebenfalls einbruchsicher mit Nebelsicherung ausgestattet.  <\/p>\n\n\n\n<p>Lisbet H\u00f8gh hat vor kurzem eine brandneue Apotheke im ehemaligen Bahnhofsgeb\u00e4ude in Kolind er\u00f6ffnet, das in der N\u00e4he des Flughafens von Aarhus, D\u00e4nemark, liegt.\nIn der Apotheke wurden die R\u00e4ume auch mit einer Nebelsicherung gegen Einbruch gesichert. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-der-roboter-verschwindet-im-nebel\"><strong>Der Roboter verschwindet im Nebel  <\/strong><\/h3>\n\n\n\n<p>Als man sich entschied, in der Apotheke sowohl einen Roboter als auch einen Nebelschutz einzusetzen, musste man beweisen, dass die beiden Technologien zusammenarbeiten k\u00f6nnen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"760\" height=\"415\" data-src=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/03\/1500i-c-fog-cannon-from-protect-.jpg\" alt=\"\" class=\"wp-image-4017 lazyload\" data-srcset=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/03\/1500i-c-fog-cannon-from-protect-.jpg 760w, https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/03\/1500i-c-fog-cannon-from-protect--420x229.jpg 420w, https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/03\/1500i-c-fog-cannon-from-protect--300x164.jpg 300w\" data-sizes=\"(max-width: 760px) 100vw, 760px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 760px; --smush-placeholder-aspect-ratio: 760\/415;\" \/><\/figure>\n\n\n\n<p>Ein Einbruch wurde simuliert und innerhalb von f\u00fcnf oder zehn Sekunden konnten Sie den Raum mit dem Roboter nicht erreichen.\nWie der Rest der Apotheke war er mit einem dichten und undurchdringlichen Nebel gef\u00fcllt, der es unm\u00f6glich machte, den Roboter und die Medikamente zu finden.\nUnd genauso wichtig ist, dass sie nach dem Test alle R\u00e4ume gel\u00fcftet haben, wie es sich geh\u00f6rt.\nJede Spur des Nebels war verschwunden.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-die-bedeutung-des-sicherheitsnebels-in-apotheken\"><strong>Die Bedeutung des Sicherheitsnebels in Apotheken<\/strong><\/h3>\n\n\n\n<p>Apotheken tragen eine gro\u00dfe Verantwortung gegen\u00fcber der \u00d6ffentlichkeit, um sicherzustellen, dass Medikamente nicht in die falschen H\u00e4nde geraten, z. B. auf den Schwarzmarkt oder in die H\u00e4nde potenzieller Drogenabh\u00e4ngiger.\nSicherheitsnebel hilft, dies zu verhindern, indem er bei Einbr\u00fcchen eine undurchdringliche Barriere bildet. <\/p>\n\n\n\n<p>Dar\u00fcber hinaus begrenzt die Nebelsicherheit die Sch\u00e4den am Gesch\u00e4ft und reduziert so m\u00f6gliche Schlie\u00dfungszeiten.\nDies ist von entscheidender Bedeutung, denn auch wenn die Versicherung den Verlust gestohlener Gegenst\u00e4nde abdecken kann, ist der Gewinnverlust aufgrund der Schlie\u00dfung des Gesch\u00e4fts nicht abgedeckt.\nDie Aufrechterhaltung eines ununterbrochenen Betriebs ist f\u00fcr die Aufrechterhaltung des Gesch\u00e4ftsbetriebs und der Rentabilit\u00e4t von entscheidender Bedeutung.  <\/p>\n\n\n\n<p>Au\u00dferdem tr\u00e4gt der Sicherheitsnebel dazu bei, das Vertrauen der Bev\u00f6lkerung in die Apotheke zu erhalten und zeigt, dass die Apotheke ihre Verantwortung ernst nimmt.\nIndem sie proaktiv Einbr\u00fcche verhindert, zeigt die Apotheke ihr Engagement f\u00fcr den Schutz der \u00f6ffentlichen Gesundheit und die Aufrechterhaltung einer sicheren und vertrauensw\u00fcrdigen Umgebung f\u00fcr ihre Kunden. <\/p>\n\n\n\n<p>&#8222;Wir haben eine Menge f\u00fcr die Sicherheit getan.\nAber allein die Vermeidung von Einbruchsversuchen ist das alles wert&#8220;, sagt Lisbet H\u00f8gh, die f\u00fchrende Apothekerin. <\/p>\n\n\n\n<p><strong>Sind Sie daran interessiert, Ihre Apotheke mit modernster Nebelsicherheitstechnologie zu sch\u00fctzen?  <\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/protectglobal.com\/de\/kontakt-aufnehmen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kontaktieren Sie uns<\/a> noch heute, um mehr dar\u00fcber zu erfahren, wie unsere Nebelkanonen Ihr Unternehmen sch\u00fctzen und die Sicherheit Ihrer wertvollen Medikamente gew\u00e4hrleisten k\u00f6nnen.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":11545,"template":"","case-category":[138],"class_list":["post-20462","case","type-case","status-publish","has-post-thumbnail","hentry","case-category-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apotheke - PROTECT Nebelkanonen\u2122<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protectglobal.com\/de\/case\/apotheke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apotheke\" \/>\n<meta property=\"og:description\" content=\"Positive Erfahrungen mit Nebelsicherheit f\u00fchren zu neuen Installationen in der Kolind Apotheke in D\u00e4nemark Nachdem die Apothekerin Lisbet H\u00f8gh in der Vergangenheit gute Erfahrungen mit Nebelschutz gemacht hat, hat sie beschlossen, in ihrem neuen Gesch\u00e4ftszentrum in der d\u00e4nischen Stadt Kolind Nebelkanonen zu installieren. Der Nebel ist sowohl mit den Medikamenten als auch mit dem pharmazeutischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protectglobal.com\/de\/case\/apotheke\/\" \/>\n<meta property=\"og:site_name\" content=\"PROTECT Nebelkanonen\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PROTECTFogCannon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T13:17:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/nathaniel-yeo-747ndboawny-unsplash-1024x684.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PROTECTFOG\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/\",\"name\":\"Apotheke - PROTECT Nebelkanonen\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg\",\"datePublished\":\"2024-05-22T11:30:39+00:00\",\"dateModified\":\"2024-12-16T13:17:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg\",\"width\":5969,\"height\":3985,\"caption\":\"pharmacy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/case\\\/apotheke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apotheke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/\",\"name\":\"PROTECT Fog Cannons\u2122\",\"description\":\"Buchen Sie ein unverbindliches Einf\u00fchrungsgespr\u00e4ch mit PROTECT und sehen Sie, wie unsere Nebelkanonen Ihr Unternehmen in Sekunden sch\u00fctzen. In nur 30 Minuten erkl\u00e4ren wir die Technik, passende L\u00f6sungen und beantworten Ihre Fragen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#organization\",\"name\":\"PROTECT Fog Cannons\u2122\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/protectglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo.svg\",\"width\":90,\"height\":40,\"caption\":\"PROTECT Fog Cannons\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/protectglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PROTECTFogCannon\\\/\",\"https:\\\/\\\/x.com\\\/PROTECTFOG\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protect-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PROTECTFogCannon\"],\"description\":\"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.\",\"email\":\"info@protectglobal.com\",\"telephone\":\"+45 8672 1881\",\"legalName\":\"PROTECT A\\\/S\",\"foundingDate\":\"2000-09-28\",\"vatID\":\"25687272\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apotheke - PROTECT Nebelkanonen\u2122","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protectglobal.com\/de\/case\/apotheke\/","og_locale":"de_DE","og_type":"article","og_title":"Apotheke","og_description":"Positive Erfahrungen mit Nebelsicherheit f\u00fchren zu neuen Installationen in der Kolind Apotheke in D\u00e4nemark Nachdem die Apothekerin Lisbet H\u00f8gh in der Vergangenheit gute Erfahrungen mit Nebelschutz gemacht hat, hat sie beschlossen, in ihrem neuen Gesch\u00e4ftszentrum in der d\u00e4nischen Stadt Kolind Nebelkanonen zu installieren. Der Nebel ist sowohl mit den Medikamenten als auch mit dem pharmazeutischen [&hellip;]","og_url":"https:\/\/protectglobal.com\/de\/case\/apotheke\/","og_site_name":"PROTECT Nebelkanonen\u2122","article_publisher":"https:\/\/www.facebook.com\/PROTECTFogCannon\/","article_modified_time":"2024-12-16T13:17:12+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/nathaniel-yeo-747ndboawny-unsplash-1024x684.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PROTECTFOG","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/","url":"https:\/\/protectglobal.com\/de\/case\/apotheke\/","name":"Apotheke - PROTECT Nebelkanonen\u2122","isPartOf":{"@id":"https:\/\/protectglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/#primaryimage"},"image":{"@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/#primaryimage"},"thumbnailUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg","datePublished":"2024-05-22T11:30:39+00:00","dateModified":"2024-12-16T13:17:12+00:00","breadcrumb":{"@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protectglobal.com\/de\/case\/apotheke\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/#primaryimage","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2024\/05\/nathaniel-yeo-747ndboawny-unsplash-scaled.jpg","width":5969,"height":3985,"caption":"pharmacy"},{"@type":"BreadcrumbList","@id":"https:\/\/protectglobal.com\/de\/case\/apotheke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/protectglobal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Apotheke"}]},{"@type":"WebSite","@id":"https:\/\/protectglobal.com\/de\/#website","url":"https:\/\/protectglobal.com\/de\/","name":"PROTECT Fog Cannons\u2122","description":"Buchen Sie ein unverbindliches Einf\u00fchrungsgespr\u00e4ch mit PROTECT und sehen Sie, wie unsere Nebelkanonen Ihr Unternehmen in Sekunden sch\u00fctzen. In nur 30 Minuten erkl\u00e4ren wir die Technik, passende L\u00f6sungen und beantworten Ihre Fragen.","publisher":{"@id":"https:\/\/protectglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protectglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/protectglobal.com\/de\/#organization","name":"PROTECT Fog Cannons\u2122","url":"https:\/\/protectglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/protectglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","contentUrl":"https:\/\/protectglobal.com\/wp-content\/uploads\/2023\/10\/logo.svg","width":90,"height":40,"caption":"PROTECT Fog Cannons\u2122"},"image":{"@id":"https:\/\/protectglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PROTECTFogCannon\/","https:\/\/x.com\/PROTECTFOG","https:\/\/www.linkedin.com\/company\/protect-a-s\/","https:\/\/www.youtube.com\/user\/PROTECTFogCannon"],"description":"PROTECT\u2122 specializes in security fog solutions, protecting valuables in retail, banks, warehouses any many other industries across more than 50 countries. With over 175,000 fog cannons installed, our systems fill rooms with dense fog in seconds, deterring burglars and preventing theft. We focus on providing reliable, durable, and easy-to-install solutions for enhanced security and peace of mind.","email":"info@protectglobal.com","telephone":"+45 8672 1881","legalName":"PROTECT A\/S","foundingDate":"2000-09-28","vatID":"25687272","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/case\/20462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/media\/11545"}],"wp:attachment":[{"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/media?parent=20462"}],"wp:term":[{"taxonomy":"case-category","embeddable":true,"href":"https:\/\/protectglobal.com\/de\/wp-json\/wp\/v2\/case-category?post=20462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}